{"id":29,"count":1,"description":"Apparel, caps, embroidery","link":"https:\/\/falconecreativedesign.com\/bge\/category\/apparel\/embroidery\/","name":"Caps, embroidery","slug":"embroidery","taxonomy":"category","parent":7,"meta":[],"_links":{"self":[{"href":"https:\/\/falconecreativedesign.com\/bge\/wp-json\/wp\/v2\/categories\/29","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/falconecreativedesign.com\/bge\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/falconecreativedesign.com\/bge\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/falconecreativedesign.com\/bge\/wp-json\/wp\/v2\/categories\/7"}],"wp:post_type":[{"href":"https:\/\/falconecreativedesign.com\/bge\/wp-json\/wp\/v2\/posts?categories=29"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}