{"id":30,"count":1,"description":"Jackets, appliques, outerwear","link":"https:\/\/falconecreativedesign.com\/bge\/category\/apparel\/jackets-outerwear\/","name":"Jackets, appliqu\u00e9s, outerwear","slug":"jackets-outerwear","taxonomy":"category","parent":7,"meta":[],"_links":{"self":[{"href":"https:\/\/falconecreativedesign.com\/bge\/wp-json\/wp\/v2\/categories\/30","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/falconecreativedesign.com\/bge\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/falconecreativedesign.com\/bge\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/falconecreativedesign.com\/bge\/wp-json\/wp\/v2\/categories\/7"}],"wp:post_type":[{"href":"https:\/\/falconecreativedesign.com\/bge\/wp-json\/wp\/v2\/posts?categories=30"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}