{"id":44,"count":0,"description":"","link":"https:\/\/falconecreativedesign.com\/bge\/category\/promote\/","name":"PROMOTE","slug":"promote","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/falconecreativedesign.com\/bge\/wp-json\/wp\/v2\/categories\/44","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/falconecreativedesign.com\/bge\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/falconecreativedesign.com\/bge\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/falconecreativedesign.com\/bge\/wp-json\/wp\/v2\/posts?categories=44"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}