{"id":1152,"date":"2016-07-13T21:25:14","date_gmt":"2016-07-13T21:25:14","guid":{"rendered":"https:\/\/falconecreativedesign.com\/bge\/wp-content\/uploads\/2016\/07\/7blog.jpg"},"modified":"2016-07-14T12:56:55","modified_gmt":"2016-07-14T12:56:55","slug":"7blog","status":"inherit","type":"attachment","link":"https:\/\/falconecreativedesign.com\/bge\/floor-decals\/7blog\/","title":{"rendered":"BGE adds a bright floor decal in Community Voice Middle School (aka CoVo) which easily welcomes all students and faculty."},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-1152","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/falconecreativedesign.com\/bge\/wp-content\/uploads\/2016\/07\/7blog.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"125\" src=\"https:\/\/falconecreativedesign.com\/bge\/wp-content\/uploads\/2016\/07\/7blog-300x125.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/falconecreativedesign.com\/bge\/wp-content\/uploads\/2016\/07\/7blog-300x125.jpg 300w, https:\/\/falconecreativedesign.com\/bge\/wp-content\/uploads\/2016\/07\/7blog-768x320.jpg 768w, https:\/\/falconecreativedesign.com\/bge\/wp-content\/uploads\/2016\/07\/7blog.jpg 840w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>BGE adds a bright floor decal in Community Voice Middle School (aka CoVo) which easily welcomes all students and faculty. <\/p>\n"},"caption":{"rendered":"<p>BGE adds a bright floor decal in Community Voice Middle School (aka CoVo) which easily welcomes all students and faculty. <\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":840,"height":350,"file":"2016\/07\/7blog.jpg","sizes":{"thumbnail":{"file":"7blog-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/falconecreativedesign.com\/bge\/wp-content\/uploads\/2016\/07\/7blog-150x150.jpg"},"medium":{"file":"7blog-300x125.jpg","width":300,"height":125,"mime_type":"image\/jpeg","source_url":"https:\/\/falconecreativedesign.com\/bge\/wp-content\/uploads\/2016\/07\/7blog-300x125.jpg"},"medium_large":{"file":"7blog-768x320.jpg","width":768,"height":320,"mime_type":"image\/jpeg","source_url":"https:\/\/falconecreativedesign.com\/bge\/wp-content\/uploads\/2016\/07\/7blog-768x320.jpg"},"full":{"file":"7blog.jpg","width":840,"height":350,"mime_type":"image\/jpeg","source_url":"https:\/\/falconecreativedesign.com\/bge\/wp-content\/uploads\/2016\/07\/7blog.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":1151,"source_url":"https:\/\/falconecreativedesign.com\/bge\/wp-content\/uploads\/2016\/07\/7blog.jpg","_links":{"self":[{"href":"https:\/\/falconecreativedesign.com\/bge\/wp-json\/wp\/v2\/media\/1152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/falconecreativedesign.com\/bge\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/falconecreativedesign.com\/bge\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/falconecreativedesign.com\/bge\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/falconecreativedesign.com\/bge\/wp-json\/wp\/v2\/comments?post=1152"}]}}